
{"id":5563,"date":"2024-09-10T15:02:03","date_gmt":"2024-09-10T19:02:03","guid":{"rendered":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/"},"modified":"2024-09-10T15:02:03","modified_gmt":"2024-09-10T19:02:03","slug":"activite-rassembleuse-a-lecole-belleau-gagnon","status":"publish","type":"post","link":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/","title":{"rendered":"Activit\u00e9 rassembleuse \u00e0 l&rsquo;\u00e9cole Belleau, Gagnon"},"content":{"rendered":"\n\n<div class=\"wp-block-post-date\"><time datetime=\"2024-09-10T15:02:03-04:00\">10 septembre 2024<\/time><\/div>\n\n\n<p class=\"wp-block-paragraph\">Parents, enfants, membres du personnel et membres de la communaut\u00e9 de Saint-Henri se sont r\u00e9unis \u00e0 l&rsquo;\u00e9cole Belleau, Gagnon de Saint-Henri, le 6 septembre dernier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beaucoup de plaisir \u00e9tait au rendez-vous! Bravo au comit\u00e9 organisateur!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n\n<div class=\"align act-mosaic-gallery\" id=\"testimonial-block_47bd45bec751d7ca4b0ba11ac1b3eda7\">\n            \n    <div class=\"act-popup-mosaic-slider\" id=\"act-popup-mosaic-slider_6a0494f237c3e\">\n        <div class=\"act-popup-mosaic-slider__wrapper\">\n            <button class=\"act-popup-mosaic-slider__btn-close\">\n                <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\">\n                    <title>Fermer<\/title>\n                    <path d=\"M25.312 8.563l-7.437 7.437 7.437 7.437-1.875 1.875-7.437-7.437-7.437 7.437-1.875-1.875 7.437-7.437-7.437-7.437 1.875-1.875 7.437 7.437 7.437-7.437z\"><\/path>\n                <\/svg>\n            <\/button>\n            <div class=\"act-popup-mosaic-slider__content\">\n                <section class=\"act-galerie-slider\">\n                    <ul id=\"act-galerie-slider_6a0494f237f89\">\n                                                                                            <\/ul>\n                <\/section>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Parents, enfants, membres du personnel et membres de la communaut\u00e9 de Saint-Henri se sont r\u00e9unis \u00e0 l&rsquo;\u00e9cole Belleau, Gagnon de Saint-Henri, le 6 septembre dernier.<\/p>\n","protected":false},"author":173,"featured_media":5564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-5563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activit\u00e9 rassembleuse \u00e0 l&#039;\u00e9cole Belleau, Gagnon - \u00c9cole Belleau, Gagnon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activit\u00e9 rassembleuse \u00e0 l&#039;\u00e9cole Belleau, Gagnon - \u00c9cole Belleau, Gagnon\" \/>\n<meta property=\"og:description\" content=\"Parents, enfants, membres du personnel et membres de la communaut\u00e9 de Saint-Henri se sont r\u00e9unis \u00e0 l&#039;\u00e9cole Belleau, Gagnon de Saint-Henri, le 6 septembre dernier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9cole Belleau, Gagnon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100076456800743\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-10T19:02:03+00:00\" \/>\n<meta name=\"author\" content=\"fortinm60@cssdn.gouv.qc.ca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"fortinm60@cssdn.gouv.qc.ca\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/\"},\"author\":{\"name\":\"fortinm60@cssdn.gouv.qc.ca\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#\\\/schema\\\/person\\\/c33219a6c041a825a50ee8ca8c59df50\"},\"headline\":\"Activit\u00e9 rassembleuse \u00e0 l&rsquo;\u00e9cole Belleau, Gagnon\",\"datePublished\":\"2024-09-10T19:02:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/\"},\"wordCount\":41,\"publisher\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2024\\\/09\\\/IMG_8936-scaled-1.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/\",\"name\":\"Activit\u00e9 rassembleuse \u00e0 l'\u00e9cole Belleau, Gagnon - \u00c9cole Belleau, Gagnon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2024\\\/09\\\/IMG_8936-scaled-1.jpg\",\"datePublished\":\"2024-09-10T19:02:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2024\\\/09\\\/IMG_8936-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2024\\\/09\\\/IMG_8936-scaled-1.jpg\",\"width\":2560,\"height\":1756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/2024\\\/09\\\/10\\\/activite-rassembleuse-a-lecole-belleau-gagnon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activit\u00e9 rassembleuse \u00e0 l&rsquo;\u00e9cole Belleau, Gagnon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#website\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/\",\"name\":\"\u00c9cole Belleau, Gagnon\",\"description\":\"Un site des centres de services scolaires des Navigateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#organization\",\"name\":\"\u00c9cole Belleau, Gagnon\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2023\\\/01\\\/logo_quebec.svg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2023\\\/01\\\/logo_quebec.svg\",\"width\":188,\"height\":41,\"caption\":\"\u00c9cole Belleau, Gagnon\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100076456800743\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/#\\\/schema\\\/person\\\/c33219a6c041a825a50ee8ca8c59df50\",\"name\":\"fortinm60@cssdn.gouv.qc.ca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/belleaugagnon\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"caption\":\"fortinm60@cssdn.gouv.qc.ca\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activit\u00e9 rassembleuse \u00e0 l'\u00e9cole Belleau, Gagnon - \u00c9cole Belleau, Gagnon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/","og_locale":"fr_CA","og_type":"article","og_title":"Activit\u00e9 rassembleuse \u00e0 l'\u00e9cole Belleau, Gagnon - \u00c9cole Belleau, Gagnon","og_description":"Parents, enfants, membres du personnel et membres de la communaut\u00e9 de Saint-Henri se sont r\u00e9unis \u00e0 l'\u00e9cole Belleau, Gagnon de Saint-Henri, le 6 septembre dernier.","og_url":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/","og_site_name":"\u00c9cole Belleau, Gagnon","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100076456800743","article_published_time":"2024-09-10T19:02:03+00:00","author":"fortinm60@cssdn.gouv.qc.ca","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"fortinm60@cssdn.gouv.qc.ca"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/#article","isPartOf":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/"},"author":{"name":"fortinm60@cssdn.gouv.qc.ca","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#\/schema\/person\/c33219a6c041a825a50ee8ca8c59df50"},"headline":"Activit\u00e9 rassembleuse \u00e0 l&rsquo;\u00e9cole Belleau, Gagnon","datePublished":"2024-09-10T19:02:03+00:00","mainEntityOfPage":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/"},"wordCount":41,"publisher":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#organization"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/#primaryimage"},"thumbnailUrl":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/uploads\/sites\/41\/2024\/09\/IMG_8936-scaled-1.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/","url":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/","name":"Activit\u00e9 rassembleuse \u00e0 l'\u00e9cole Belleau, Gagnon - \u00c9cole Belleau, Gagnon","isPartOf":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/#primaryimage"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/#primaryimage"},"thumbnailUrl":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/uploads\/sites\/41\/2024\/09\/IMG_8936-scaled-1.jpg","datePublished":"2024-09-10T19:02:03+00:00","breadcrumb":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/#primaryimage","url":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/uploads\/sites\/41\/2024\/09\/IMG_8936-scaled-1.jpg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/uploads\/sites\/41\/2024\/09\/IMG_8936-scaled-1.jpg","width":2560,"height":1756},{"@type":"BreadcrumbList","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/2024\/09\/10\/activite-rassembleuse-a-lecole-belleau-gagnon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/"},{"@type":"ListItem","position":2,"name":"Activit\u00e9 rassembleuse \u00e0 l&rsquo;\u00e9cole Belleau, Gagnon"}]},{"@type":"WebSite","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#website","url":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/","name":"\u00c9cole Belleau, Gagnon","description":"Un site des centres de services scolaires des Navigateurs","publisher":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#organization","name":"\u00c9cole Belleau, Gagnon","url":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#\/schema\/logo\/image\/","url":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/uploads\/sites\/41\/2023\/01\/logo_quebec.svg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/uploads\/sites\/41\/2023\/01\/logo_quebec.svg","width":188,"height":41,"caption":"\u00c9cole Belleau, Gagnon"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100076456800743"]},{"@type":"Person","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/#\/schema\/person\/c33219a6c041a825a50ee8ca8c59df50","name":"fortinm60@cssdn.gouv.qc.ca","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","url":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","caption":"fortinm60@cssdn.gouv.qc.ca"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:12:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/posts\/5563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/users\/173"}],"replies":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/comments?post=5563"}],"version-history":[{"count":0,"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/posts\/5563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/media\/5564"}],"wp:attachment":[{"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/media?parent=5563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/categories?post=5563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/belleaugagnon\/wp-json\/wp\/v2\/tags?post=5563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}