
{"id":5705,"date":"2025-04-03T09:29:34","date_gmt":"2025-04-03T13:29:34","guid":{"rendered":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/"},"modified":"2025-04-03T09:29:34","modified_gmt":"2025-04-03T13:29:34","slug":"code-dethique-applicable-a-tous-les-membres-du-personnel","status":"publish","type":"post","link":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/","title":{"rendered":"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel"},"content":{"rendered":"\n\n<div class=\"wp-block-post-date\"><time datetime=\"2025-04-03T09:29:34-04:00\">3 avril 2025<\/time><\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" data-src=\"https:\/\/cssdn.gouv.qc.ca\/wp-content\/uploads\/2025\/04\/Bandeau_code_ethique.jpg\" alt=\"\" class=\"wp-image-15084 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cette semaine, le Centre de services scolaire des Navigateurs a partag\u00e9 son nouveau code d&rsquo;\u00e9thique \u00e0 tous ses membres du personnel et \u00e0 toute personne appel\u00e9e \u00e0 \u0153uvrer aupr\u00e8s d\u2019\u00e9l\u00e8ves mineurs ou handicap\u00e9s ou \u00e0 \u00eatre en contact avec eux. Cela inclut, de fa\u00e7on non limitative, les stagiaires, les superviseurs de stage, les b\u00e9n\u00e9voles, les entra\u00eeneurs, les responsables d\u2019activit\u00e9s parascolaires ou toute autre personne offrant des services en vertu d\u2019une entente ou d\u2019un contrat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le code d\u2019\u00e9thique a pour objectif :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>d\u2019\u00e9tablir un guide de r\u00e9f\u00e9rence quant aux pratiques et conduites attendues de la part de tous les membres du personnel du CSSDN et de toute personne appel\u00e9e \u00e0 y \u0153uvrer aupr\u00e8s d\u2019\u00e9l\u00e8ves mineurs ou handicap\u00e9s ou \u00e0 \u00eatre en contact avec eux;<\/li>\n\n\n\n<li>de constituer un outil de r\u00e9flexion et de responsabilisation pour encourager le jugement critique aux fins de la prise de d\u00e9cision propice au d\u00e9veloppement de valeurs morales et d\u2019une \u00e9thique professionnelle;<\/li>\n\n\n\n<li>d\u2019\u00e9tablir et de cultiver le lien de confiance des \u00e9l\u00e8ves, des parents, de la communaut\u00e9 \u00e9ducative et du public en g\u00e9n\u00e9ral envers le CSSDN, ses \u00e9tablissements et le syst\u00e8me \u00e9ducatif.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque personne vis\u00e9e par cette politique doit conna\u00eetre et comprendre les normes d\u2019\u00e9thique ainsi que les pratiques et conduites qui sont attendues, en plus de s\u2019engager \u00e0 les respecter et \u00e0 en promouvoir le respect.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Direction g\u00e9n\u00e9rale ainsi que les directions d\u2019\u00e9tablissement et de services sont responsables de la diffusion et de la promotion du pr\u00e9sent code d\u2019\u00e9thique aupr\u00e8s des membres du personnel et de toute personne appel\u00e9e \u00e0 \u0153uvrer aupr\u00e8s d\u2019\u00e9l\u00e8ves mineurs ou handicap\u00e9s ou \u00e0 \u00eatre en contact avec eux qui \u00e9voluent dans leur \u00e9tablissement ou leur unit\u00e9 administrative pour en assurer l\u2019application.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez le pr\u00e9sent code, disponible \u00e0 tout le monde, dans notre\u00a0site Internet\u00a0sous l\u2019onglet \u00ab\u00a0Le CSSDN\u00a0\u00bb, dans la section relative aux \u00ab\u00a0Lois, r\u00e8glements et politiques\u00a0\u00bb ainsi que dans l\u2019intranet.\u00a0<\/p>\n\n\n\n<div class=\"is-content-justification-center wp-block-buttons\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cssdn.gouv.qc.ca\/wp-content\/uploads\/2025\/03\/Code-dethique-adopte-CA-25-mars-2025.pdf\">Code d&rsquo;\u00e9thique du CSSDN<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cette semaine, le Centre de services scolaire des Navigateurs a partag\u00e9 son nouveau code d&rsquo;\u00e9thique \u00e0 tous ses membres du personnel et \u00e0 toute personne appel\u00e9e \u00e0 \u0153uvrer aupr\u00e8s d\u2019\u00e9l\u00e8ves mineurs ou handicap\u00e9s ou \u00e0 \u00eatre en contact avec eux.<\/p>\n","protected":false},"author":173,"featured_media":5706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-5705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel - \u00c9coles de la Berge, du Ch\u00eane, de la Falaise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel - \u00c9coles de la Berge, du Ch\u00eane, de la Falaise\" \/>\n<meta property=\"og:description\" content=\"Cette semaine, le Centre de services scolaire des Navigateurs a partag\u00e9 son nouveau code d&#039;\u00e9thique \u00e0 tous ses membres du personnel et \u00e0 toute personne appel\u00e9e \u00e0 \u0153uvrer aupr\u00e8s d\u2019\u00e9l\u00e8ves mineurs ou handicap\u00e9s ou \u00e0 \u00eatre en contact avec eux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9coles de la Berge, du Ch\u00eane, de la Falaise\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bergechenefalaise\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-03T13:29:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/uploads\/sites\/23\/2025\/04\/Vignette_Site_code_ethique.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"407\" \/>\n\t<meta property=\"og:image:height\" content=\"253\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fortinm60@cssdn.gouv.qc.ca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"fortinm60@cssdn.gouv.qc.ca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/\"},\"author\":{\"name\":\"fortinm60@cssdn.gouv.qc.ca\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#\\\/schema\\\/person\\\/c33219a6c041a825a50ee8ca8c59df50\"},\"headline\":\"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel\",\"datePublished\":\"2025-04-03T13:29:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/\"},\"wordCount\":365,\"publisher\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/04\\\/Vignette_Site_code_ethique.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/\",\"name\":\"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel - \u00c9coles de la Berge, du Ch\u00eane, de la Falaise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/04\\\/Vignette_Site_code_ethique.jpg\",\"datePublished\":\"2025-04-03T13:29:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/04\\\/Vignette_Site_code_ethique.jpg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/04\\\/Vignette_Site_code_ethique.jpg\",\"width\":407,\"height\":253},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/2025\\\/04\\\/03\\\/code-dethique-applicable-a-tous-les-membres-du-personnel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#website\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/\",\"name\":\"\u00c9coles de la Berge, du Ch\u00eane, de la Falaise\",\"description\":\"Un site des centres de services scolaires des Navigateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#organization\",\"name\":\"\u00c9coles de la Berge, du Ch\u00eane, de la Falaise\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/01\\\/logo_quebec.svg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/01\\\/logo_quebec.svg\",\"width\":188,\"height\":41,\"caption\":\"\u00c9coles de la Berge, du Ch\u00eane, de la Falaise\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bergechenefalaise\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/#\\\/schema\\\/person\\\/c33219a6c041a825a50ee8ca8c59df50\",\"name\":\"fortinm60@cssdn.gouv.qc.ca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/chenebergefalaise\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"caption\":\"fortinm60@cssdn.gouv.qc.ca\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel - \u00c9coles de la Berge, du Ch\u00eane, de la Falaise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/","og_locale":"fr_CA","og_type":"article","og_title":"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel - \u00c9coles de la Berge, du Ch\u00eane, de la Falaise","og_description":"Cette semaine, le Centre de services scolaire des Navigateurs a partag\u00e9 son nouveau code d'\u00e9thique \u00e0 tous ses membres du personnel et \u00e0 toute personne appel\u00e9e \u00e0 \u0153uvrer aupr\u00e8s d\u2019\u00e9l\u00e8ves mineurs ou handicap\u00e9s ou \u00e0 \u00eatre en contact avec eux.","og_url":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/","og_site_name":"\u00c9coles de la Berge, du Ch\u00eane, de la Falaise","article_publisher":"https:\/\/www.facebook.com\/bergechenefalaise","article_published_time":"2025-04-03T13:29:34+00:00","og_image":[{"width":407,"height":253,"url":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/uploads\/sites\/23\/2025\/04\/Vignette_Site_code_ethique.jpg","type":"image\/jpeg"}],"author":"fortinm60@cssdn.gouv.qc.ca","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"fortinm60@cssdn.gouv.qc.ca","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/#article","isPartOf":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/"},"author":{"name":"fortinm60@cssdn.gouv.qc.ca","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#\/schema\/person\/c33219a6c041a825a50ee8ca8c59df50"},"headline":"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel","datePublished":"2025-04-03T13:29:34+00:00","mainEntityOfPage":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/"},"wordCount":365,"publisher":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#organization"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/#primaryimage"},"thumbnailUrl":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/uploads\/sites\/23\/2025\/04\/Vignette_Site_code_ethique.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/","url":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/","name":"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel - \u00c9coles de la Berge, du Ch\u00eane, de la Falaise","isPartOf":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/#primaryimage"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/#primaryimage"},"thumbnailUrl":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/uploads\/sites\/23\/2025\/04\/Vignette_Site_code_ethique.jpg","datePublished":"2025-04-03T13:29:34+00:00","breadcrumb":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/#primaryimage","url":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/uploads\/sites\/23\/2025\/04\/Vignette_Site_code_ethique.jpg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/uploads\/sites\/23\/2025\/04\/Vignette_Site_code_ethique.jpg","width":407,"height":253},{"@type":"BreadcrumbList","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/2025\/04\/03\/code-dethique-applicable-a-tous-les-membres-du-personnel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/"},{"@type":"ListItem","position":2,"name":"Code d\u2019\u00e9thique applicable \u00e0 tous les membres du personnel"}]},{"@type":"WebSite","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#website","url":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/","name":"\u00c9coles de la Berge, du Ch\u00eane, de la Falaise","description":"Un site des centres de services scolaires des Navigateurs","publisher":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#organization","name":"\u00c9coles de la Berge, du Ch\u00eane, de la Falaise","url":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#\/schema\/logo\/image\/","url":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/uploads\/sites\/23\/2023\/01\/logo_quebec.svg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/uploads\/sites\/23\/2023\/01\/logo_quebec.svg","width":188,"height":41,"caption":"\u00c9coles de la Berge, du Ch\u00eane, de la Falaise"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bergechenefalaise"]},{"@type":"Person","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/#\/schema\/person\/c33219a6c041a825a50ee8ca8c59df50","name":"fortinm60@cssdn.gouv.qc.ca","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","url":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","caption":"fortinm60@cssdn.gouv.qc.ca"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:00:41","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/posts\/5705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/users\/173"}],"replies":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/comments?post=5705"}],"version-history":[{"count":0,"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/posts\/5705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/media\/5706"}],"wp:attachment":[{"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/media?parent=5705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/categories?post=5705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/chenebergefalaise\/wp-json\/wp\/v2\/tags?post=5705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}