
{"id":5484,"date":"2023-11-08T16:35:02","date_gmt":"2023-11-08T21:35:02","guid":{"rendered":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/"},"modified":"2023-11-08T16:35:02","modified_gmt":"2023-11-08T21:35:02","slug":"rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements","status":"publish","type":"post","link":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/","title":{"rendered":"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un message aux parents et \u00e9l\u00e8ves de tous les niveaux, concernant l\u2019information relative \u00e0 la fermeture de nos \u00e9tablissements en cas de temp\u00eate de neige, de verglas ou d\u2019intemp\u00e9ries majeures, vient d&rsquo;\u00eatre d\u00e9pos\u00e9 dans <a href=\"https:\/\/cssdn.gouv.qc.ca\/parents-et-eleves\/messages-aux-parents\/\">la page \u00ab Messages aux parents \u00bb<\/a> du Centre de services scolaire des Navigateurs. Cliquez sur \u00ab Lire le message \u00bb pour visionner le fichier PDF.<\/p>\n\n\n\n<div class=\"wp-block-buttons\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/cssdn.gouv.qc.ca\/wp-content\/uploads\/2023\/11\/20231108-CSSDN-fermeture-tempete.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Lire le message<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un message aux parents et \u00e9l\u00e8ves de tous les niveaux, concernant l\u2019information relative \u00e0 la fermeture de nos \u00e9tablissements en cas de temp\u00eate de neige, de verglas ou d\u2019intemp\u00e9ries majeures, vient d&rsquo;\u00eatre d\u00e9pos\u00e9 dans la page \u00ab Messages aux parents \u00bb.<\/p>\n","protected":false},"author":173,"featured_media":5485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-5484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements - \u00c9cole Clair-Soleil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements - \u00c9cole Clair-Soleil\" \/>\n<meta property=\"og:description\" content=\"Un message aux parents et \u00e9l\u00e8ves de tous les niveaux, concernant l\u2019information relative \u00e0 la fermeture de nos \u00e9tablissements en cas de temp\u00eate de neige, de verglas ou d\u2019intemp\u00e9ries majeures, vient d&#039;\u00eatre d\u00e9pos\u00e9 dans la page \u00ab Messages aux parents \u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9cole Clair-Soleil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063489011162\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-08T21:35:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/uploads\/sites\/24\/2023\/11\/Messages-DG-Juste-photos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1640\" \/>\n\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fortinm60@cssdn.gouv.qc.ca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"fortinm60@cssdn.gouv.qc.ca\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/\"},\"author\":{\"name\":\"fortinm60@cssdn.gouv.qc.ca\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#\\\/schema\\\/person\\\/c33219a6c041a825a50ee8ca8c59df50\"},\"headline\":\"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements\",\"datePublished\":\"2023-11-08T21:35:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/\"},\"wordCount\":77,\"publisher\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/11\\\/Messages-DG-Juste-photos.jpg\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/\",\"name\":\"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements - \u00c9cole Clair-Soleil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/11\\\/Messages-DG-Juste-photos.jpg\",\"datePublished\":\"2023-11-08T21:35:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/11\\\/Messages-DG-Juste-photos.jpg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/11\\\/Messages-DG-Juste-photos.jpg\",\"width\":1640,\"height\":924},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/2023\\\/11\\\/08\\\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#website\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/\",\"name\":\"\u00c9cole Clair-Soleil\",\"description\":\"Un site du Centre de services scolaires des Navigateurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#organization\",\"name\":\"\u00c9cole Clair-Soleil\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/01\\\/logo_quebec.svg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/01\\\/logo_quebec.svg\",\"width\":188,\"height\":41,\"caption\":\"\u00c9cole Clair-Soleil\"},\"image\":{\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063489011162\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/#\\\/schema\\\/person\\\/c33219a6c041a825a50ee8ca8c59df50\",\"name\":\"fortinm60@cssdn.gouv.qc.ca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"url\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"contentUrl\":\"https:\\\/\\\/cssdn.gouv.qc.ca\\\/clairsoleil\\\/wp-content\\\/wphb-cache\\\/gravatar\\\/2d6\\\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg\",\"caption\":\"fortinm60@cssdn.gouv.qc.ca\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements - \u00c9cole Clair-Soleil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/","og_locale":"fr_CA","og_type":"article","og_title":"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements - \u00c9cole Clair-Soleil","og_description":"Un message aux parents et \u00e9l\u00e8ves de tous les niveaux, concernant l\u2019information relative \u00e0 la fermeture de nos \u00e9tablissements en cas de temp\u00eate de neige, de verglas ou d\u2019intemp\u00e9ries majeures, vient d'\u00eatre d\u00e9pos\u00e9 dans la page \u00ab Messages aux parents \u00bb.","og_url":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/","og_site_name":"\u00c9cole Clair-Soleil","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063489011162","article_published_time":"2023-11-08T21:35:02+00:00","og_image":[{"width":1640,"height":924,"url":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/uploads\/sites\/24\/2023\/11\/Messages-DG-Juste-photos.jpg","type":"image\/jpeg"}],"author":"fortinm60@cssdn.gouv.qc.ca","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"fortinm60@cssdn.gouv.qc.ca"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/#article","isPartOf":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/"},"author":{"name":"fortinm60@cssdn.gouv.qc.ca","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#\/schema\/person\/c33219a6c041a825a50ee8ca8c59df50"},"headline":"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements","datePublished":"2023-11-08T21:35:02+00:00","mainEntityOfPage":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/"},"wordCount":77,"publisher":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#organization"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/#primaryimage"},"thumbnailUrl":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/uploads\/sites\/24\/2023\/11\/Messages-DG-Juste-photos.jpg","articleSection":["Uncategorized"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/","url":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/","name":"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements - \u00c9cole Clair-Soleil","isPartOf":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/#primaryimage"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/#primaryimage"},"thumbnailUrl":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/uploads\/sites\/24\/2023\/11\/Messages-DG-Juste-photos.jpg","datePublished":"2023-11-08T21:35:02+00:00","breadcrumb":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/#primaryimage","url":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/uploads\/sites\/24\/2023\/11\/Messages-DG-Juste-photos.jpg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/uploads\/sites\/24\/2023\/11\/Messages-DG-Juste-photos.jpg","width":1640,"height":924},{"@type":"BreadcrumbList","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/2023\/11\/08\/rappels-importants-en-cas-de-tempete-ou-de-fermeture-detablissements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/"},{"@type":"ListItem","position":2,"name":"Rappels importants en cas de temp\u00eate ou de fermeture d\u2019\u00e9tablissements"}]},{"@type":"WebSite","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#website","url":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/","name":"\u00c9cole Clair-Soleil","description":"Un site du Centre de services scolaires des Navigateurs","publisher":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#organization","name":"\u00c9cole Clair-Soleil","url":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#\/schema\/logo\/image\/","url":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/uploads\/sites\/24\/2023\/01\/logo_quebec.svg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/uploads\/sites\/24\/2023\/01\/logo_quebec.svg","width":188,"height":41,"caption":"\u00c9cole Clair-Soleil"},"image":{"@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063489011162"]},{"@type":"Person","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/#\/schema\/person\/c33219a6c041a825a50ee8ca8c59df50","name":"fortinm60@cssdn.gouv.qc.ca","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","url":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","contentUrl":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-content\/wphb-cache\/gravatar\/2d6\/2d6f6effeb5d333ee07a9fb7a982f633x96.jpg","caption":"fortinm60@cssdn.gouv.qc.ca"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:13:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/posts\/5484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/users\/173"}],"replies":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/comments?post=5484"}],"version-history":[{"count":0,"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/posts\/5484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/media\/5485"}],"wp:attachment":[{"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/media?parent=5484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/categories?post=5484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cssdn.gouv.qc.ca\/clairsoleil\/wp-json\/wp\/v2\/tags?post=5484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}